{"id":301125,"date":"2023-06-12T17:09:19","date_gmt":"2023-06-12T21:09:19","guid":{"rendered":"https:\/\/www.participaction.com\/?p=301125"},"modified":"2023-10-10T15:38:22","modified_gmt":"2023-10-10T19:38:22","slug":"activite-physique-et-le-sport-pour-tous","status":"publish","type":"post","link":"https:\/\/dev.participaction.com\/fr\/blog\/activite-physique-et-le-sport-pour-tous\/","title":{"rendered":"L\u2019activit\u00e9 physique et le sport pour tous"},"content":{"rendered":"<p>[et_pb_section fb_built=&#x201D;1&#x2033; admin_label=&#x201D;section&#x201D; _builder_version=&#x201D;4.16&#x2033; global_colors_info=&#x201D;{}&#x201D;][et_pb_row admin_label=&#x201D;row&#x201D; _builder_version=&#x201D;4.16&#x2033; background_size=&#x201D;initial&#x201D; background_position=&#x201D;top_left&#x201D; background_repeat=&#x201D;repeat&#x201D; global_colors_info=&#x201D;{}&#x201D;][et_pb_column type=&#x201D;4_4&#x2033; _builder_version=&#x201D;4.16&#x2033; custom_padding=&#x201D;|||&#x201D; global_colors_info=&#x201D;{}&#x201D; custom_padding__hover=&#x201D;|||&#x201D;][et_pb_text _builder_version=&#x201D;4.18.0&#x2033; _module_preset=&#x201D;default&#x201D; global_colors_info=&#x201D;{}&#x201D;]<\/p>\n<p>Saviez-vous que pr&#xE8;s de <a href=\"https:\/\/www150.statcan.gc.ca\/n1\/pub\/89-654-x\/89-654-x2018002-fra.htm\" target=\"_blank\" rel=\"noopener\">4&#xA0;% des enfants et 13&#xA0;% des jeunes<\/a> au Canada vivent avec un handicap? Globalement, les enfants et les jeunes ayant un handicap pratiquent moins d&#x2019;activit&#xE9;s physiques que ceux qui n&#x2019;en ont pas.<\/p>\n<p>Le manque d&#x2019;occasions favorisant la pleine participation des enfants et aux jeunes en situation de handicap &#xE0; des activit&#xE9;s physiques demeure un enjeu de sant&#xE9; publique et des droits de l&#x2019;homme. Dans le <a href=\"https:\/\/cdpp.ca\/resources-and-publications\/canadian-physical-activity-report-card-children-adolescents-disabilities\" target=\"_blank\" rel=\"noopener\">Bulletin canadien de l&#x2019;activit&#xE9; physique chez les enfants et les adolescents en situation de handicap<\/a>, ces derniers ont re&ccedil;u la note D pour l&rsquo;<a class=\"glossaryLink\"  title=\"Glossary: Activit&eacute; physique\"  aria-describedby=\"tt\"  data-cmtooltip=\"&lt;div class=glossaryItemBody&gt;Tout mouvement corporel produit par les muscles squelettiques qui entra&icirc;ne une augmentation de la d&eacute;pense &eacute;nerg&eacute;tique et qui augmente la fr&eacute;quence cardiaque et le rythme respiratoire.&amp;lt;br \/&amp;gt;&amp;lt;strong&amp;gt;R&eacute;f&eacute;rence:&amp;lt;\/strong&amp;gt; &amp;lt;a href=&amp;quot;https:\/\/www.ncbi.nlm.nih.gov\/pubmed\/3920711&amp;quot;&amp;gt;https:\/\/www.ncbi.nlm.nih.gov\/pubmed\/3920711&amp;lt;\/a&amp;gt;&lt;\/div&gt;\"  href=\"https:\/\/dev.participaction.com\/fr\/glossary\/physical-activity\/\"  data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]'  tabindex='0' role='link'>activit&eacute; physique<\/a> globale, la note F pour le <a class=\"glossaryLink\"  title=\"Glossary: Jeu actif\"  aria-describedby=\"tt\"  data-cmtooltip=\"&lt;div class=glossaryItemBody&gt;&amp;lt;span style=&amp;quot;font-weight: 400;&amp;quot;&amp;gt;Concept similaire &agrave; celui de l&rsquo;activit&eacute; physique d&rsquo;intensit&eacute; moyenne &agrave; &eacute;lev&eacute;e (APME), mais qui est plus appropri&eacute; au contexte des jeunes enfants. Il fait r&eacute;f&eacute;rence aux activit&eacute;s physiques pour jeunes enfants qui les font s&rsquo;activer avec intensit&eacute;, s&rsquo;essouffler et avoir chaud.&amp;lt;\/span&amp;gt;&amp;lt;br \/&amp;gt;&amp;lt;b&amp;gt;R&eacute;f&eacute;rence:&nbsp;&amp;lt;\/b&amp;gt;&amp;lt;a href=&amp;quot;http:\/\/www.csep.ca\/en\/guidelines\/glossary-2017&amp;quot;&amp;gt;&amp;lt;span style=&amp;quot;font-weight: 400;&amp;quot;&amp;gt;http:\/\/www.csep.ca\/en\/guidelines\/glossary-2017&amp;lt;\/span&amp;gt;&amp;lt;\/a&amp;gt;&lt;\/div&gt;\"  href=\"https:\/\/dev.participaction.com\/fr\/glossary\/energetic-or-active-play\/\"  data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]'  tabindex='0' role='link'>jeu actif<\/a> et la note C+ pour le sport organis&eacute; et l&rsquo;activit&eacute; physique.<\/p>\n<p>Vous aimeriez savoir comment rendre l&#x2019;activit&#xE9; physique et le sport plus accessibles aux personnes en situation de handicap? Nous avons demand&#xE9; &#xE0; deux experts en mati&#xE8;re d&#x2019;inclusion et d&#x2019;accessibilit&#xE9;, <a href=\"https:\/\/www.parasportontario.ca\/people\/dave-sora\" target=\"_blank\" rel=\"noopener\">Dave Sora<\/a> et Katie Disimino, de nous faire part de leurs recommandations.<\/p>\n<p>Dave Sora est coresponsable du Parcours de participation &#xE0; l&#x2019;Ontario Parasport Collective, cofondateur et vice-pr&#xE9;sident du <a href=\"https:\/\/www.sportandplay.ca\/#:~:text=The%20Centre%20for%20Accessible%20Sport,quality%20sport%20and%20recreation%20programming.\" target=\"_blank\" rel=\"noopener\">Centre pour l&#x2019;accessibilit&#xE9; du sport et du jeu<\/a>, responsable de <a href=\"https:\/\/kidsaction.ca\/\" target=\"_blank\" rel=\"noopener\">KidsAction Coaching<\/a> en Ontario, responsable de <a href=\"https:\/\/jooay.com\/\" target=\"_blank\" rel=\"noopener\">Jooay<\/a> en Ontario et membre du <a href=\"https:\/\/cdpp.ca\/\" target=\"_blank\" rel=\"noopener\">projet canadien sur la participation sociale des personnes en situation de handicap<\/a>. Depuis 2008, il a travaill&#xE9; aupr&#xE8;s de clubs sportifs, de chercheurs et d&#x2019;organisations &#xE0; travers le Canada afin de trouver des moyens de faire jouer les enfants en situation de handicap, notamment &#xE0; travers l&#x2019;innovation.<\/p>\n<p><img decoding=\"async\" class=\"wp-image-301130 size-medium aligncenter\" title=\"Dave Sora dans un uniforme d&#x2019;entra&#xEE;neur.\" src=\"https:\/\/dev.participaction.com\/wp-content\/uploads\/2023\/06\/20150503_140451-1-220x300.jpg\" alt=\"Dave Sora dans un uniforme d&#x2019;entra&#xEE;neur.\" width=\"220\" height=\"300\" srcset=\"https:\/\/dev.participaction.com\/wp-content\/uploads\/2023\/06\/20150503_140451-1-220x300.jpg 220w, https:\/\/dev.participaction.com\/wp-content\/uploads\/2023\/06\/20150503_140451-1.jpg 426w\" sizes=\"(max-width: 220px) 100vw, 220px\"\/><\/p>\n<p>Katie Disimino est doctorante &#xE0; l&#x2019;&#xE9;cole de kin&#xE9;siologie et de sciences de la sant&#xE9; de l&#x2019;universit&#xE9; York. Ses recherches portent sur la promotion de l&#x2019;activit&#xE9; physique et elle est membre du comit&#xE9; de recherche sur l&#x2019;accessibilit&#xE9; de ParticipACTION. Katie a &#xE9;galement fait partie d&#x2019;une &#xE9;quipe de recherche qui a &#xE9;labor&#xE9; des recommandations pour aider les organisations &#xE0; promouvoir l&#x2019;activit&#xE9; physique chez les enfants et les jeunes en situation de handicap.<\/p>\n<p><img decoding=\"async\" class=\"wp-image-301132 size-medium aligncenter\" title=\"Katie Disimino souriant devant un buisson en plein air.\" src=\"https:\/\/dev.participaction.com\/wp-content\/uploads\/2023\/06\/IMG_7303-1-300x241.jpg\" alt=\"Katie Disimino souriant devant un buisson en plein air.\" width=\"300\" height=\"241\"\/><\/p>\n<h3><span style=\"color: #50287d;\"><strong>Quels sont les principaux d&#xE9;fis et obstacles auxquels les personnes vivant avec un handicap sont confront&#xE9;es lorsqu&#x2019;il s&#x2019;agit d&#x2019;acc&#xE9;der &#xE0; l&#x2019;activit&#xE9; physique et au sport? <\/strong><\/span><\/h3>\n<p><strong>Dave&#xA0;:<\/strong> Les personnes en situation de handicap, les enfants en particulier, sont confront&#xE9;es &#xE0; des d&#xE9;fis et &#xE0; des obstacles uniques qui ont un impact sur leur participation, leur exp&#xE9;rience et le plaisir dans le sport et l&#x2019;activit&#xE9; physique. Les obstacles les plus courants sont la discrimination, l&#x2019;inaccessibilit&#xE9; des installations et des services, les co&#xFB;ts &#xE9;lev&#xE9;s, l&#x2019;&#xE9;loignement et la n&#xE9;cessit&#xE9; d&#x2019;un &#xE9;quipement sp&#xE9;cial. Il existe trois autres obstacles &#xE0; la participation, moins connus, du c&#xF4;t&#xE9; de l&#x2019;offre&#xA0;: le manque de programmes adapt&#xE9;s de qualit&#xE9;, le choix limit&#xE9; de types de programmes et le manque d&#x2019;entra&#xEE;neurs, de b&#xE9;n&#xE9;voles et d&#x2019;animateurs form&#xE9;s au sein de la communaut&#xE9;. Malheureusement, tous les indicateurs sugg&#xE8;rent que la pand&#xE9;mie a entra&#xEE;n&#xE9; des r&#xE9;percussions n&#xE9;gatives sur le taux d&#x2019;activit&#xE9; physique et de participation chez les personnes en situation de handicap, qui &#xE9;tait d&#xE9;j&#xE0; faible. En effet, elles ont &#xE9;t&#xE9; les premi&#xE8;res &#xE0; partir et les derni&#xE8;res &#xE0; revenir. Le retour au jeu des enfants vivant avec un handicap au jeu ne semble pas une priorit&#xE9; au sein des organisations.<\/p>\n<p><img decoding=\"async\" class=\"wp-image-301134 size-medium aligncenter\" title=\"Une femme jouant au tennis en fauteuil roulant sur un terrain ext&#xE9;rieur en terre battue.\" src=\"https:\/\/dev.participaction.com\/wp-content\/uploads\/2023\/06\/shutterstock_1156479532-1-300x200.jpg\" alt=\"Une femme jouant au tennis en fauteuil roulant sur un terrain ext&#xE9;rieur en terre battue.\" width=\"300\" height=\"200\"\/><\/p>\n<p><strong>Katie :<\/strong> L&#x2019;acc&#xE8;s in&#xE9;quitable aux possibilit&#xE9;s d&#x2019;activit&#xE9; physique, le manque d&#x2019;informations pertinentes sur l&#x2019;activit&#xE9; physique, le co&#xFB;t des programmes adapt&#xE9;s et de l&#x2019;&#xE9;quipement sp&#xE9;cialis&#xE9; ne sont que quelques-uns des nombreux obstacles auxquels sont confront&#xE9;es les personnes vivant avec un handicap.<\/p>\n<h3><span style=\"color: #50287d;\"><strong>Comment les organisations telles que les &#xE9;coles, les centres communautaires, les gymnases et les clubs sportifs peuvent-elles rendre leurs installations et leurs programmes plus accessibles?<\/strong><\/span><\/h3>\n<p><strong>Dave&#xA0;:<\/strong> Lorsqu&#x2019;on parle d&#x2019;accessibilit&#xE9;, il est important de comprendre que l&#x2019;acc&#xE8;s physique ne repr&#xE9;sente qu&#x2019;une petite partie. Le fait qu&#x2019;une installation soit accessible ne rend pas automatiquement le programme ou le service accessible, et ne contribue pas non plus &#xE0; augmenter la qualit&#xE9; de la participation et des exp&#xE9;riences v&#xE9;cues. Les organisations peuvent envisager quelques strat&#xE9;gies ou approches&#xA0;:<\/p>\n<ol>\n<li><strong>Voir plus loin que les b&#xE2;timents<\/strong>: &#xE9;tudier la diff&#xE9;rence entre &#xAB;&#xA0;rendre quelque chose accessible&#xA0;&#xBB; et &#xAB;&#xA0;cr&#xE9;er de merveilleuses exp&#xE9;riences&#xA0;&#xBB;. Ce n&#x2019;est pas parce qu&#x2019;une personne peut acc&#xE9;der &#xE0; un b&#xE2;timent qu&#x2019;elle va y vivre une exp&#xE9;rience exceptionnelle.<\/li>\n<li><strong>Adopter la philosophie &#xAB;&#xA0;rien sans nous&#xA0;&#xBB;<\/strong>: inclure les personnes et les employ&#xE9;s en situation de handicap dans la planification des strat&#xE9;gies d&#x2019;am&#xE9;lioration de l&#x2019;accessibilit&#xE9;.<\/li>\n<li><strong>&#xC9;largir le champ d&#x2019;action &#xE0; &#xAB;&#xA0;tout le monde joue&#xA0;&#xBB;<\/strong>: mieux comprendre et appr&#xE9;cier la complexit&#xE9; des obstacles, en particulier les obstacles cach&#xE9;s, qui peuvent exister au-del&#xE0; de l&#x2019;environnement physique et s&#x2019;&#xE9;tendre &#xE0; l&#x2019;environnement social et &#xE0; l&#x2019;environnement des programmes.<\/li>\n<li><strong>Faire preuve de cr&#xE9;ativit&#xE9; et d&#x2019;initiative<\/strong>: adopter une approche &#xAB;&#xA0;innovante&#xA0;&#xBB; face aux obstacles et solutions, &#xEA;tre cr&#xE9;atif et favoriser le changement.<\/li>\n<li><strong>Communiquer de mani&#xE8;re inclusive<\/strong>: veillez &#xE0; communiquer &#xE0; tout le monde ce que vous faites pour am&#xE9;liorer l&#x2019;accessibilit&#xE9; et assurer vous que l&#x2019;information soit accessible, qu&#x2019;il s&#x2019;agisse du site web, des programmes, des &#xE9;v&#xE9;nements ou des rapports annuels. Il ne sert &#xE0; rien d&#x2019;avoir des installations et des programmes accessibles si les personnes que vous essayez de joindre ne peuvent pas acc&#xE9;der &#xE0; l&#x2019;information.<\/li>\n<li><strong>Travailler ensemble<\/strong>: recherchez des personnes et des organisations dans votre communaut&#xE9; et dans l&#x2019;ensemble du secteur du sport et des services aux personnes en situation de handicap qui sont d&#xE9;sireuses de vous aider et de partager ou de vous orienter vers des ressources.<\/li>\n<\/ol>\n<p><strong>Katie :<\/strong> Veiller &#xE0; ce que les installations r&#xE9;pondent aux besoins de mobilit&#xE9; des participants des programmes. Cr&#xE9;er des installations spacieuses, d&#xE9;gag&#xE9;es, bien &#xE9;clair&#xE9;es, dot&#xE9;es d&#x2019;indicateurs tactiles de surface de marche, d&#x2019;ascenseurs et de rampes d&#x2019;acc&#xE8;s. Proposer des &#xE9;quipements sp&#xE9;cialis&#xE9;s ou adaptables, tels que des fauteuils de sport, des ballons sonores, des poign&#xE9;es velcro pour les halt&#xE8;res et des filets r&#xE9;glables. S&#x2019;assurer que les b&#xE9;n&#xE9;voles et le personnel sont en mesure de modifier les activit&#xE9;s, les instructions et l&#x2019;&#xE9;quipement en fonction des capacit&#xE9;s des participants et qu&#x2019;ils savent quand et comment le faire.<\/p>\n<p><img decoding=\"async\" class=\"wp-image-301136 size-medium aligncenter\" title=\"Un appareil soul&#xE8;ve un homme de son fauteuil roulant pour le faire entrer dans une piscine couverte.\" src=\"https:\/\/dev.participaction.com\/wp-content\/uploads\/2023\/06\/shutterstock_281189456-1-300x199.jpg\" alt=\"Un appareil soul&#xE8;ve un homme de son fauteuil roulant pour le faire entrer dans une piscine couverte.\" width=\"300\" height=\"199\"\/><\/p>\n<p>Il est &#xE9;galement important de partager des informations sur les programmes dans diff&#xE9;rents formats, notamment sous forme de texte, d&#x2019;images et de sons, et de veiller &#xE0; ce que les programmes offrent des chances &#xE9;gales de participation aux personnes de toutes capacit&#xE9;s.<\/p>\n<h3><span style=\"color: #50287d;\"><strong>Quels sont les meilleurs moyens d&#x2019;encourager les personnes en situation de handicap &#xE0; pratiquer un sport ou une activit&#xE9; physique?<\/strong><\/span><\/h3>\n<p><strong>Dave&#xA0;:<\/strong> La recherche et la pratique ont mis en &#xE9;vidence de nombreuses strat&#xE9;gies efficaces pour accro&#xEE;tre la participation des personnes en situation de handicap&#xA0;:<\/p>\n<ul>\n<li>Concevoir des programmes qui favorisent une &#xAB;&#xA0;participation de qualit&#xE9;&#xA0;&#xBB; et qui mettent l&#x2019;accent sur le &#xAB;&#xA0;sentiment d&#x2019;appartenance&#xA0;&#xBB;.<\/li>\n<li>&#xC9;laborer des documents et des informations accessibles sur les programmes.<\/li>\n<li>Veiller &#xE0; ce que les personnes en situation de handicap soient refl&#xE9;t&#xE9;es et repr&#xE9;sent&#xE9;es dans les produits de communication et le mat&#xE9;riel de sensibilisation.<\/li>\n<li>Concevoir une communication adapt&#xE9;e aux besoins et aux attentes des participants en incluant des d&#xE9;tails sur la signification du terme &#xAB;&#xA0;inclusif&#xA0;&#xBB;, sur les types d&#x2019;adaptations et d&#x2019;am&#xE9;nagements et enfin sur la s&#xE9;curit&#xE9;.<\/li>\n<li>Mettre en &#x153;uvre des strat&#xE9;gies de recrutement personnalis&#xE9;es et cibl&#xE9;es.<\/li>\n<li>Reconna&#xEE;tre la valeur de la programmation en ligne\/virtuelle en tant que voie de participation accessible.<\/li>\n<li>Utiliser des outils et des formations en ligne, des orientations pr&#xE9;alables aux programmes et des s&#xE9;ances d&#x2019;essai multisports afin d&#x2019;assurer une entr&#xE9;e s&#xE9;curitaire et confortable dans le jeu.<\/li>\n<li>Pr&#xEA;tez attention au concept de &#xAB;&#xA0;premi&#xE8;re participation&#xA0;&#xBB; afin de cr&#xE9;er une premi&#xE8;re exp&#xE9;rience positive et de favoriser la fid&#xE9;lisation.<\/li>\n<li>Recueillir et partager des t&#xE9;moignages.<\/li>\n<li>Organiser des journ&#xE9;es &#xAB;&#xA0;Amenez un ami&#xA0;&#xBB;.<\/li>\n<\/ul>\n<p><strong>Katie :<\/strong> Communiquer des informations claires et d&#xE9;taill&#xE9;es sur les programmes d&#x2019;activit&#xE9; physique, le personnel, les installations et les avantages sp&#xE9;cifiques de l&#x2019;activit&#xE9; physique pour les personnes en situation de handicap. Partager des id&#xE9;es, des outils et des ressources pour soutenir la participation &#xE0; l&#x2019;activit&#xE9; physique, l&#x2019;&#xE9;tablissement d&#x2019;objectifs, la planification et le suivi des progr&#xE8;s.<\/p>\n<p><img decoding=\"async\" class=\"wp-image-301138 size-medium aligncenter\" title=\"Un homme jouant au goalball, un sport adapt&#xE9; con&#xE7;u pour les personnes ayant une d&#xE9;ficience visuelle.\" src=\"https:\/\/dev.participaction.com\/wp-content\/uploads\/2023\/06\/shutterstock_1221173368-1-300x200.jpg\" alt=\"Un homme jouant au goalball, un sport adapt&#xE9; con&#xE7;u pour les personnes ayant une d&#xE9;ficience visuelle.\" width=\"300\" height=\"200\"\/><\/p>\n<h3><span style=\"color: #50287d;\"><strong>Quels conseils donneriez-vous aux personnes ou aux organisations souhaitant accro&#xEE;tre l&#x2019;accessibilit&#xE9; de l&#x2019;activit&#xE9; physique et du sport au sein de leur communaut&#xE9;?<\/strong><\/span><\/h3>\n<p><strong>Dave&#xA0;:<\/strong><\/p>\n<ul>\n<li>Ne pas se casser la t&#xEA;te&#xA0;: l&#x2019;objectif peut &#xEA;tre aussi simple que de se faire un nouvel ami&#x2009;; ce n&#x2019;est pas une question de comp&#xE9;tences, de performances ou de comp&#xE9;titions. Le plaisir et les amiti&#xE9;s suffisent amplement. Si vous voulez commencer quelque chose, faites-le, car cela n&#x2019;arrivera pas tout seul.<\/li>\n<li>L&#x2019;impact est relatif&#xA0;: il ne s&#x2019;agit pas toujours d&#x2019;engager et de mobiliser un grand nombre de personnes. Comprenez et appr&#xE9;ciez l&#x2019;impact extraordinaire et souvent incommensurable qu&#x2019;il y a &#xE0; offrir des occasions de jeu ne serait-ce qu&#x2019;&#xE0; un seul enfant en situation de handicap &#x2013; cela peut changer une vie.<\/li>\n<li>S&#x2019;appuyer sur les autres&#xA0;: il existe de nombreuses organisations sportives, agences de services et personnes partageant des objectifs communs qui sont d&#xE9;sireuses de partager leur expertise et leurs ressources pour favoriser l&#x2019;activit&#xE9; physique.<\/li>\n<\/ul>\n<p>Pour plus de conseils sur la mani&#xE8;re de rendre l&#x2019;activit&#xE9; physique et le sport plus accessibles, consultez ces ressources&#xA0;:<\/p>\n<ul>\n<li><a href=\"https:\/\/cdpp.ca\/\" target=\"_blank\" rel=\"noopener\">Le projet canadien sur la participation sociale des personnes en situation de handicap<\/a> (anglais)<\/li>\n<li><a href=\"https:\/\/cdpp.ca\/resources-and-publications\/canadian-physical-activity-report-card-children-adolescents-disabilities\" target=\"_blank\" rel=\"noopener\">Bulletin canadien de l&#x2019;activit&#xE9; physique chez les enfants et les adolescents en situation de handicap <\/a><u>(anglais)<\/u><\/li>\n<li><a href=\"https:\/\/www.aimpa.ca\/\" target=\"_blank\" rel=\"noopener\">Aider, informer et encourager l&#x2019;activit&#xE9; physique &#x2013; AIMPA<\/a> (anglais)<\/li>\n<li><a href=\"https:\/\/dev.participaction.com\/fr\/blogue\/voici-5-sports-des-plus-accessibles\/\">Voici 5&#xA0;sports des plus accessibles pour tout le monde<\/a><\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vous aimeriez savoir comment rendre l&#x2019;activit&#xE9; physique et le sport plus accessibles aux personnes en situation de handicap? Nous avons demand&#xE9; &#xE0; deux experts en mati&#xE8;re d&#x2019;inclusion et d&#x2019;accessibilit&#xE9; de nous faire part de leurs recommandations.<\/p>\n","protected":false},"author":21,"featured_media":301065,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","content-type":"","footnotes":""},"categories":[464,987,189],"tags":[994,399,407,741,132,127],"benefits":[],"class_list":["post-301125","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inclusion","category-accessibilite","category-sports-fr","tag-accessibilite","tag-enfants","tag-inclusion-fr","tag-jeunes","tag-sport-fr","tag-trucs-et-conseils"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.participaction.com\/fr\/wp-json\/wp\/v2\/posts\/301125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.participaction.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.participaction.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.participaction.com\/fr\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.participaction.com\/fr\/wp-json\/wp\/v2\/comments?post=301125"}],"version-history":[{"count":0,"href":"https:\/\/dev.participaction.com\/fr\/wp-json\/wp\/v2\/posts\/301125\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.participaction.com\/fr\/wp-json\/wp\/v2\/media\/301065"}],"wp:attachment":[{"href":"https:\/\/dev.participaction.com\/fr\/wp-json\/wp\/v2\/media?parent=301125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.participaction.com\/fr\/wp-json\/wp\/v2\/categories?post=301125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.participaction.com\/fr\/wp-json\/wp\/v2\/tags?post=301125"},{"taxonomy":"benefits","embeddable":true,"href":"https:\/\/dev.participaction.com\/fr\/wp-json\/wp\/v2\/benefits?post=301125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}