{"id":267963,"date":"2022-02-01T15:13:39","date_gmt":"2022-02-01T20:13:39","guid":{"rendered":"https:\/\/www.participaction.com\/4-ways-to-keep-your-kids-and-you-active-this-winter\/"},"modified":"2023-12-15T11:16:15","modified_gmt":"2023-12-15T16:16:15","slug":"4-facons-de-garder-vos-enfants-et-vous-meme-actifs-cet-hiver","status":"publish","type":"post","link":"https:\/\/dev.participaction.com\/fr\/blog\/4-facons-de-garder-vos-enfants-et-vous-meme-actifs-cet-hiver\/","title":{"rendered":"4 fa\u00e7ons de garder vos enfants (et vous-m\u00eame!) actifs cet hiver"},"content":{"rendered":"<p>[et_pb_section fb_built=&#x201D;1&#x2033; admin_label=&#x201D;section&#x201D; _builder_version=&#x201D;4.16&#x2033; global_colors_info=&#x201D;{}&#x201D;][et_pb_row admin_label=&#x201D;row&#x201D; _builder_version=&#x201D;4.16&#x2033; background_size=&#x201D;initial&#x201D; background_position=&#x201D;top_left&#x201D; background_repeat=&#x201D;repeat&#x201D; global_colors_info=&#x201D;{}&#x201D;][et_pb_column type=&#x201D;4_4&#x2033; _builder_version=&#x201D;4.16&#x2033; custom_padding=&#x201D;|||&#x201D; global_colors_info=&#x201D;{}&#x201D; custom_padding__hover=&#x201D;|||&#x201D;][et_pb_text _builder_version=&#x201D;4.18.0&#x2033; _module_preset=&#x201D;default&#x201D; global_colors_info=&#x201D;{}&#x201D;]<\/p>\n<p>Les hivers froids et les journ&eacute;es plus courtes peuvent entra&icirc;ner de nombreux probl&egrave;mes de sant&eacute; mentale, en partie en raison des conditions hivernales qui font parfois obstacle &agrave; l&rsquo;<a class=\"glossaryLink\"  title=\"Glossary: Activit&eacute; physique\"  aria-describedby=\"tt\"  data-cmtooltip=\"&lt;div class=glossaryItemBody&gt;Tout mouvement corporel produit par les muscles squelettiques qui entra&icirc;ne une augmentation de la d&eacute;pense &eacute;nerg&eacute;tique et qui augmente la fr&eacute;quence cardiaque et le rythme respiratoire.&amp;lt;br \/&amp;gt;&amp;lt;strong&amp;gt;R&eacute;f&eacute;rence:&amp;lt;\/strong&amp;gt; &amp;lt;a href=&amp;quot;https:\/\/www.ncbi.nlm.nih.gov\/pubmed\/3920711&amp;quot;&amp;gt;https:\/\/www.ncbi.nlm.nih.gov\/pubmed\/3920711&amp;lt;\/a&amp;gt;&lt;\/div&gt;\"  href=\"https:\/\/dev.participaction.com\/fr\/glossary\/physical-activity\/\"  data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]'  tabindex='0' role='link'>activit&eacute; physique<\/a> &agrave; l&rsquo;ext&eacute;rieur. Toutefois, &ecirc;tre actif &agrave; l&rsquo;ext&eacute;rieur peut nous aider &agrave; g&eacute;rer le stress et &agrave; am&eacute;liorer notre sant&eacute; mentale et physique.<\/p>\n<p>En hiver, nous devrions embo&#xEE;ter le pas de nos enfants, chez qui cette saison suscite souvent un enthousiasme d&#xE9;bordant! Le grand manteau blanc de l&#x2019;hiver offre un terrain de jeu et d&#x2019;activit&#xE9;s renouvel&#xE9; pour les enfants! Voici quelques-unes des fa&#xE7;ons les plus agr&#xE9;ables de garder vos enfants (et vous-m&#xEA;me!) actifs cet hiver&#xA0;:<\/p>\n<h3 style=\"text-align: left;\"><img decoding=\"async\" class=\"wp-image-270245 alignright size-medium\" src=\"https:\/\/dev.participaction.com\/wp-content\/uploads\/2022\/02\/83481d84-b09d-45f5-aff0-312ea154171e_Toboggan-300x200.png\" alt=\"family having fun in the snow\" width=\"300\" height=\"200\"\/>1. Faire du toboggan<\/h3>\n<p>Faire du toboggan consiste &#xE0; descendre une colline enneig&#xE9;e sur une surface glissante, comme sur un tapis &#xE0; neige en plastique ou sur un tra&#xEE;neau. Le toboggan &#xE9;tait utilis&#xE9; par les Inuits et les Cris du nord du Canada bien avant qu&#x2019;il ne serve d&#x2019;activit&#xE9; r&#xE9;cr&#xE9;ative. En effet, ces peuples s&#x2019;en servaient autrefois pour transporter des enfants et des vivres sur la neige. Les toboggans modernes sont habituellement fabriqu&#xE9;s en bois ou en plastique et ont une base glissante pour bien glisser sur la neige. En revanche, un gros morceau de carton ou un sac &#xE0; ordures feraient aussi l&#x2019;affaire!<\/p>\n<p>Aujourd&#x2019;hui, certaines r&#xE9;gions ont interdit la glissade en toboggan parce qu&#x2019;on craint que le risque de blessures soit trop &#xE9;lev&#xE9; pour les enfants. Mais lorsque l&#x2019;activit&#xE9; est pratiqu&#xE9;e de fa&#xE7;on s&#xE9;curitaire et sous supervision, elle peut &#xEA;tre tr&#xE8;s amusante! Apportez votre toboggan au sommet d&#x2019;une colline, asseyez-vous ou couchez-vous dessus et profitez de la glissade jusqu&#x2019;en bas!<\/p>\n<h3><img decoding=\"async\" class=\"wp-image-267948 alignleft size-medium\" src=\"https:\/\/dev.participaction.com\/wp-content\/uploads\/2022\/08\/64374f29-d2d6-4842-a6a4-57e6942d4c8f_Snowballfight-300x200.png\" alt=\"family having fun and making snow balls\" width=\"300\" height=\"200\"\/>2. Faites une bataille de boule de neige<\/h3>\n<p>Les batailles de boules de neige consistent &#xE0; lancer des boules de neige aux gens pour les atteindre volontairement. Elles sont souvent anarchiques et ont tendance &#xE0; &#xE9;clater lorsqu&#x2019;on s&#x2019;y attend le moins! G&#xE9;n&#xE9;ralement, un groupe de personnes forme deux &#xE9;quipes, on fa&#xE7;onne des boules de neige et on les lance sur ses adversaires. L&#x2019;intention n&#x2019;est pas de blesser les gens de l&#x2019;autre &#xE9;quipe, mais simplement de les atteindre assez souvent pour qu&#x2019;ils abandonnent.<\/p>\n<p>Pour &#xE9;viter toute blessure, assurez-vous que les boules de neige que vous formez ne contiennent pas de pierres ni de d&#xE9;bris. De plus, ne visez jamais la t&#xEA;te de personne ni le bas de la ceinture.<\/p>\n<h3 style=\"text-align: left;\"><img decoding=\"async\" class=\"wp-image-267951 alignright size-medium\" src=\"https:\/\/dev.participaction.com\/wp-content\/uploads\/2022\/08\/04948ee1-b7ea-4ed8-b4d7-c714e4efb53e_Snowfort-300x200.png\" alt=\"kid inside a snow fort\" width=\"300\" height=\"200\"\/>3. Construisez un fort dans la neige<\/h3>\n<p style=\"text-align: left;\">Construire un fort en neige ou un igloo consiste &#xE0; fabriquer des structures &#xE0; partir de neige ou de glace. Pour former ces structures, empilez de la neige (de pr&#xE9;f&#xE9;rence de la neige souffl&#xE9;e par le vent, car elle est d&#xE9;j&#xE0; tass&#xE9;e) en forme de maison ou de d&#xF4;me. Au fil du temps, la neige fondra et reg&#xE8;lera naturellement, ce qui solidifiera votre construction. Pour des raisons de s&#xE9;curit&#xE9;, soyez accompagn&#xE9; d&#x2019;autres personnes lors de la construction et renoncez &#xE0; faire un toit pour r&#xE9;duire le risque d&#x2019;effondrement de la structure.<\/p>\n<h3 style=\"text-align: left;\"><img decoding=\"async\" class=\"wp-image-267952 alignleft size-medium\" src=\"https:\/\/dev.participaction.com\/wp-content\/uploads\/2022\/08\/f1600670-910a-438a-aa8c-0a32ab5d4ddb_Snowperson-300x200.png\" alt=\"family making a snowperson\" width=\"300\" height=\"200\"\/>4.&#xA0;Sculptez un bonhomme de neige<\/h3>\n<p>Faire un bonhomme de neige est une activit&#xE9; hivernale amusante, autant pour les enfants que pour les adultes. Cela consiste &#xE0; empiler des boules de neige les unes sur les autres. Le facteur de r&#xE9;ussite le plus important est d&#x2019;avoir de la neige collante sous la main, car la neige l&#xE9;g&#xE8;re et floconneuse ou la glace ne vous seront d&#x2019;aucune utilit&#xE9;.<\/p>\n<p>Commencez par rouler la neige pour fa&#xE7;onner trois boules de diff&#xE9;rentes tailles. Ensuite, empilez-les les unes sur les autres, de la plus grosse &#xE0; la plus petite. Puis, ajoutez des accessoires comme un chapeau, un foulard, un nez de carotte et des pierres pour les yeux et voyez votre propre Frosty ou Olaf prendre forme!<\/p>\n<p>Nous esp&#xE9;rons que ces id&#xE9;es d&#x2019;activit&#xE9;s ont fait souffler un vent de nostalgie qui vous a redonn&#xE9; envie de jouer dehors pour profiter de l&#x2019;hiver, que ce soit pour faire plaisir &#xE0; vos enfants&#x2026; o&#xF9; &#xE0; celui qui sommeille en vous! Ces activit&#xE9;s amusantes sont peut-&#xEA;tre l&#x2019;inspiration dont vous aviez besoin pour commencer (ou continuer) &#xE0; profiter de l&#x2019;hiver!<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les hivers froids et les journ&#xE9;es plus courtes peuvent entra&#xEE;ner de nombreux probl&#xE8;mes de sant&#xE9; mentale, en partie en raison des conditions hivernales qui font parfois obstacle &#xE0; l&#x2019;activit&#xE9; physique &#xE0; l&#x2019;ext&#xE9;rieur. Toutefois, &#xEA;tre actif &#xE0; l&#x2019;ext&#xE9;rieur peut nous aider &#xE0; g&#xE9;rer le stress et &#xE0; am&#xE9;liorer notre sant&#xE9; mentale et physique. En hiver, nous [&#x2026;]<\/p>\n","protected":false},"author":14,"featured_media":267956,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","content-type":"","footnotes":""},"categories":[443,42],"tags":[399,1059,413,809],"benefits":[],"class_list":["post-267963","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-en-plein-air","category-famille","tag-enfants","tag-exterieur-fr","tag-hiver","tag-luge"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.participaction.com\/fr\/wp-json\/wp\/v2\/posts\/267963","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.participaction.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.participaction.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.participaction.com\/fr\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.participaction.com\/fr\/wp-json\/wp\/v2\/comments?post=267963"}],"version-history":[{"count":0,"href":"https:\/\/dev.participaction.com\/fr\/wp-json\/wp\/v2\/posts\/267963\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.participaction.com\/fr\/wp-json\/wp\/v2\/media\/267956"}],"wp:attachment":[{"href":"https:\/\/dev.participaction.com\/fr\/wp-json\/wp\/v2\/media?parent=267963"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.participaction.com\/fr\/wp-json\/wp\/v2\/categories?post=267963"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.participaction.com\/fr\/wp-json\/wp\/v2\/tags?post=267963"},{"taxonomy":"benefits","embeddable":true,"href":"https:\/\/dev.participaction.com\/fr\/wp-json\/wp\/v2\/benefits?post=267963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}