{"id":267933,"date":"2021-10-26T14:25:05","date_gmt":"2021-10-26T18:25:05","guid":{"rendered":"https:\/\/www.participaction.com\/unleashed-and-on-the-move-2\/"},"modified":"2022-09-29T19:56:02","modified_gmt":"2022-09-29T23:56:02","slug":"dechainee-et-en-mouvement","status":"publish","type":"post","link":"https:\/\/dev.participaction.com\/fr\/blog\/dechainee-et-en-mouvement\/","title":{"rendered":"D\u00e9cha\u00een\u00e9e et en mouvement"},"content":{"rendered":"<p>[et_pb_section fb_built=&#x201D;1&#x2033; admin_label=&#x201D;section&#x201D; _builder_version=&#x201D;4.16&#x2033; global_colors_info=&#x201D;{}&#x201D;][et_pb_row admin_label=&#x201D;row&#x201D; _builder_version=&#x201D;4.16&#x2033; background_size=&#x201D;initial&#x201D; background_position=&#x201D;top_left&#x201D; background_repeat=&#x201D;repeat&#x201D; global_colors_info=&#x201D;{}&#x201D;][et_pb_column type=&#x201D;4_4&#x2033; _builder_version=&#x201D;4.16&#x2033; custom_padding=&#x201D;|||&#x201D; global_colors_info=&#x201D;{}&#x201D; custom_padding__hover=&#x201D;|||&#x201D;][et_pb_text _builder_version=&#x201D;4.17.6&#x2033; _module_preset=&#x201D;default&#x201D; global_colors_info=&#x201D;{}&#x201D;]<\/p>\n<h3 style=\"text-align: center;\">Le mode de vie de Britt Pearson au Yukon conjugue son amour pour les chiens, la vie sauvage et le fait d&#x2019;&#xEA;tre active.<\/h3>\n<p>Des montagnes spectaculaires, des points de vue panoramiques, des eaux miroitantes&#x2026;et une passionn&#xE9;e de v&#xE9;lo de montagne suivie de neuf chiens enjou&#xE9;s? Si vous passez suffisamment de temps sur les 700 kilom&#xE8;tres de sentiers de la ville de Whitehorse au Yukon, vous rencontrerez peut-&#xEA;tre Britt Pearson et sa fameuse troupe&#xA0;<em>FawkesTrot<\/em>, une bande de chiens aidants qui incarnent l&#x2019;aventure et l&#x2019;essence m&#xEA;me de la vie au Yukon.<\/p>\n<p><img decoding=\"async\" class=\"wp-image-267902 aligncenter size-full\" src=\"https:\/\/dev.participaction.com\/wp-content\/uploads\/2021\/10\/965e99f5-e693-412f-94f9-e3049bd3caaa_Resized-Picture7.jpg\" alt=\"Britt Pearson with her dogs\" width=\"1000\" height=\"652\" srcset=\"https:\/\/dev.participaction.com\/wp-content\/uploads\/2021\/10\/965e99f5-e693-412f-94f9-e3049bd3caaa_Resized-Picture7.jpg 1000w, https:\/\/dev.participaction.com\/wp-content\/uploads\/2021\/10\/965e99f5-e693-412f-94f9-e3049bd3caaa_Resized-Picture7-980x639.jpg 980w, https:\/\/dev.participaction.com\/wp-content\/uploads\/2021\/10\/965e99f5-e693-412f-94f9-e3049bd3caaa_Resized-Picture7-480x313.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1000px, 100vw\"\/><\/p>\n<p>Britt est une athl&#xE8;te multidisciplinaire du Yukon qui, pour poursuivre ses &#xE9;tudes et son go&#xFB;t de l&#x2019;aventure, s&#x2019;est aussi &#xE9;tablie &#xE0; Ottawa, Victoria, et m&#xEA;me Paris. Son amour pour le Grand Nord l&#x2019;a toutefois ramen&#xE9;e &#xE0; la maison.<\/p>\n<p>En tant qu&#x2019;ancienne skieuse de fond avec l&#x2019;&#xE9;quipe du Yukon, les vastes &#xE9;tendues de ce territoire ont toujours occup&#xE9; une place de choix dans son c&#x153;ur. Mais sa passion ne se limite pas &#xE0; son amour de la neige. &#xAB;&#xA0;Il y a tant de grands espaces silencieux, et c&#x2019;est quand vous vous &#xE9;loignez du Yukon que vous r&#xE9;alisez &#xE0; quel point &#xE7;a vous manque.&#xA0;Vous ne luttez jamais contre d&#x2019;autres gens pour trouver votre petit coin de nature sauvage ici.&#xA0;&#xBB;<\/p>\n<p>L&#x2019;entreprise de Britt est partie de son amour des paysages et de la qu&#xEA;te d&#x2019;une vie qui refl&#xE9;tait davantage sa passion pour les chiots, les affaires et le mouvement.<\/p>\n<p><img decoding=\"async\" class=\"alignright wp-image-267905\" src=\"https:\/\/dev.participaction.com\/wp-content\/uploads\/2021\/10\/71af5182-1d86-40a8-881c-035eb2ff5088_Resized-Picture6-683x1024.jpg\" alt=\"Britt Pearson posing with her nine dogs\" width=\"350\" height=\"525\"\/>Trois ans plus tard, Britt a maintenant deux employ&#xE9;s chez<em>&#xA0;FawkesTrot&#xA0;<\/em>et une liste de clients qui partagent sa philosophie que les chiens de Whitehorse m&#xE9;ritent autant de pouvoir partir &#xE0; l&#x2019;aventure que les humains. C&#x2019;est cet engagement qui a en quelque sorte transform&#xE9; Britt en une l&#xE9;gende locale. &#xAB;&#xA0;Je croise des gens dans la ville, &#xE0; un caf&#xE9; ou &#xE0; un &#xE9;v&#xE9;nement, et ils me disent : &#x2018;je regarde tes publications Instagram chaque jour. Je n&#x2019;ai m&#xEA;me pas de chien. J&#x2019;aime simplement voir les chiens courir dans les bois. C&#x2019;est comme une th&#xE9;rapie! &#x2019; &#xC7;a me r&#xE9;chauffe le c&#x153;ur.&#xA0;&#xBB;<\/p>\n<p>Elle s&#x2019;&#xE9;panouit dans son travail, &#xE9;motionnellement et physiquement. Elle fait de la randonn&#xE9;e, du v&#xE9;lo, de la course, du ski et m&#xEA;me du ski &#xE9;questre avec ses chiens, beau temps mauvais temps. Et m&#xEA;me si &#xE7;a peut para&#xEE;tre &#xE9;puisant d&#x2019;effectuer jusqu&#x2019;&#xE0; sept sorties de deux heures par semaine avec ses chiens, elle ne pourrait pas s&#x2019;en passer. Se retrouver dans cet environnement &#xE9;pique en compagnie de ses gentils toutous &#xE0; quelque chose de lib&#xE9;rateur et de purement joyeux. Et m&#xEA;me si la plupart de ces sorties sont remplies d&#x2019;adr&#xE9;naline, Britt s&#x2019;est aussi d&#xE9;couvert un petit penchant pour des activit&#xE9;s plus l&#xE9;g&#xE8;res avec ses chiens. &#xAB;&#xA0;Parfois je chante &#xE0; tue-t&#xEA;te sur les sentiers. Il n&#x2019;y a aucune honte. On est seuls dans la nature apr&#xE8;s tout! J&#x2019;ai d&#xE9;couvert les joies de la cueillette. C&#x2019;est l&#x2019;endroit parfait pour &#xE7;a. Les chiens se reposent pendant que je cueille des canneberges ou des champignons.&#xA0;&#xBB;<\/p>\n<p>Britt est en bonne compagnie, incluant la nature sauvage &#xE0; son quotidien comme de rien. Elle dit que c&#x2019;est ancr&#xE9; dans le mode de vie de beaucoup de Yukonnais. &#xAB;&#xA0;J&#x2019;aime le fait de pouvoir faire du plein air &#xE0; presque n&#x2019;importe quel moment de la journ&#xE9;e en poursuivant mes passions. Et ils sont nombreux ici &#xE0; organiser leur travail autour de la possibilit&#xE9; de profiter de ce territoire majestueux. Avoir cette nature immense &#xE0; proximit&#xE9; vous inspire &#xE0; en faire le centre de votre vie et &#xE0; s&#x2019;y attacher.&#xA0;&#xBB;<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le mode de vie de Britt Pearson au Yukon conjugue son amour pour les chiens, la vie sauvage et le fait d&#x2019;&#xEA;tre active. Des montagnes spectaculaires, des points de vue panoramiques, des eaux miroitantes&#x2026;et une passionn&#xE9;e de v&#xE9;lo de montagne suivie de neuf chiens enjou&#xE9;s? Si vous passez suffisamment de temps sur les 700 kilom&#xE8;tres [&#x2026;]<\/p>\n","protected":false},"author":14,"featured_media":267909,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","content-type":"","footnotes":""},"categories":[443,32],"tags":[408,72,178],"benefits":[],"class_list":["post-267933","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-en-plein-air","category-inspiration","tag-exterieur","tag-outdoors","tag-yukon-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.participaction.com\/fr\/wp-json\/wp\/v2\/posts\/267933","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.participaction.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.participaction.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.participaction.com\/fr\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.participaction.com\/fr\/wp-json\/wp\/v2\/comments?post=267933"}],"version-history":[{"count":0,"href":"https:\/\/dev.participaction.com\/fr\/wp-json\/wp\/v2\/posts\/267933\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.participaction.com\/fr\/wp-json\/wp\/v2\/media\/267909"}],"wp:attachment":[{"href":"https:\/\/dev.participaction.com\/fr\/wp-json\/wp\/v2\/media?parent=267933"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.participaction.com\/fr\/wp-json\/wp\/v2\/categories?post=267933"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.participaction.com\/fr\/wp-json\/wp\/v2\/tags?post=267933"},{"taxonomy":"benefits","embeddable":true,"href":"https:\/\/dev.participaction.com\/fr\/wp-json\/wp\/v2\/benefits?post=267933"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}