{"id":261574,"date":"2018-01-05T09:21:10","date_gmt":"2018-01-05T14:21:10","guid":{"rendered":"https:\/\/www.participaction.com\/?p=261574"},"modified":"2023-10-11T14:54:28","modified_gmt":"2023-10-11T18:54:28","slug":"7-conseils-pour-rester-motives","status":"publish","type":"post","link":"https:\/\/dev.participaction.com\/fr\/blog\/7-conseils-pour-rester-motives\/","title":{"rendered":"7 conseils pour rester motiv\u00e9s"},"content":{"rendered":"<p>[et_pb_section fb_built=&#x201D;1&#x2033; admin_label=&#x201D;section&#x201D; _builder_version=&#x201D;4.16&#x2033; global_colors_info=&#x201D;{}&#x201D;][et_pb_row admin_label=&#x201D;row&#x201D; _builder_version=&#x201D;4.16&#x2033; background_size=&#x201D;initial&#x201D; background_position=&#x201D;top_left&#x201D; background_repeat=&#x201D;repeat&#x201D; global_colors_info=&#x201D;{}&#x201D;][et_pb_column type=&#x201D;4_4&#x2033; _builder_version=&#x201D;4.16&#x2033; custom_padding=&#x201D;|||&#x201D; global_colors_info=&#x201D;{}&#x201D; custom_padding__hover=&#x201D;|||&#x201D;][et_pb_text admin_label=&#x201D;Text&#x201D; _builder_version=&#x201D;4.16&#x2033; background_size=&#x201D;initial&#x201D; background_position=&#x201D;top_left&#x201D; background_repeat=&#x201D;repeat&#x201D; global_colors_info=&#x201D;{}&#x201D;]La motivation peut facilement dispara&#xEE;tre. &#xC0; l&#x2019;approche de la nouvelle ann&#xE9;e, on s&#x2019;emballe et on est enthousiastes. Puis soudainement, une semaine passe et notre motivation s&#x2019;est envol&#xE9;e.<\/p>\n<p>Et on sait tous pourquoi &#x2014; faire des changements est difficile. C&#x2019;est facile de se dire qu&#x2019;on veut faire plus d&#x2019;exercice, mais c&#x2019;est plus facile &#xE0; dire qu&#x2019;&#xE0; faire, et ainsi la motivation peut s&#x2019;estomper rapidement.<\/p>\n<p>Nous vous proposons donc quelques petits conseils pour vous aider &#xE0; rester motiv&#xE9;s &#xE0; bouger.<\/p>\n<p><strong>1. TENEZ-VOUS-EN &#xC0; L&#x2019;ESSENTIEL.<\/strong><\/p>\n<p>Il y a tant d&#x2019;informations et de strat&#xE9;gies sur la motivation et le changement qu&#x2019;on peut facilement &#xEA;tre d&#xE9;pass&#xE9;s.<\/p>\n<p>Au lieu de vous laisser submerger par toutes ces infos, tenez-vous-en &#xE0; l&#x2019;essentiel. Mangez bien, dormez 7,5 &#xE0; 8 heures de sommeil de qualit&#xE9; chaque nuit, et buvez beaucoup d&#x2019;eau pendant la journ&#xE9;e. La simplicit&#xE9; aide &#xE0; se concentrer sur l&#x2019;essentiel. Quand vous &#xEA;tes hydrat&#xE9;s, bien repos&#xE9;s, et que vous vous nourrissez avec de bons nutriments, vous avez de meilleures chances d&#x2019;&#xEA;tre motiv&#xE9;s &#xE0; bouger.<\/p>\n<p><strong>2. PRIORISER LA R&#xC9;GULARIT&#xC9; PLUT&#xD4;T QUE L&#x2019;INTENSIT&#xC9;.<\/strong><\/p>\n<p>C&#x2019;est facile de partir trop rapidement ou avec trop d&#x2019;intensit&#xE9;. On pense que de grands changements n&#xE9;cessitent de grandes actions. Mais en r&#xE9;alit&#xE9;, la r&#xE9;gularit&#xE9; est bien plus significative que l&#x2019;intensit&#xE9;. Commencez par les petites choses que vous pouvez faire chaque jour. Le changement se produit lentement et &#xE0; long terme, pas du jour au lendemain. Une fois que vous serez actifs r&#xE9;guli&#xE8;rement, vous pourrez alors augmenter l&#x2019;intensit&#xE9;.<\/p>\n<p><strong>3. &#xC9;VITEZ L&#x2019;APPROCHE TOUT OU RIEN.<\/strong><\/p>\n<p>Souvent, nous jugeons rapidement nos objectifs sur une base r&#xE9;ussites\/&#xE9;checs. Soit nous y arrivons, soit nous n&#x2019;y arrivons pas. Ajoutez &#xE0; cela une nouvelle r&#xE9;solution trop ambitieuse et l&#x2019;&#xE9;chec est in&#xE9;vitable.<\/p>\n<p>Voyez plut&#xF4;t le progr&#xE8;s comme votre outil de r&#xE9;f&#xE9;rence. Est-ce que vous vous am&#xE9;liorez? Prenez-vous les moyens d&#x2019;atteindre vos objectifs? Allez-vous dans la bonne direction?<\/p>\n<p>Ne soyez pas trop durs avec vous si vous manquez une journ&#xE9;e ou si vous rencontrez un obstacle. Continuez simplement &#xE0; aller de l&#x2019;avant. L&#x2019;ann&#xE9;e est longue, et en vous souvenant que quelque chose est d&#xE9;j&#xE0; mieux que rien, vous irez loin.<\/p>\n<p><strong>4. RAPPELEZ-VOUS CE QUI EST EN JEU.<\/strong><\/p>\n<p>Parfois, nos actions sont motiv&#xE9;es non pas par pour obtenir les r&#xE9;compenses, mais plut&#xF4;t pour &#xE9;viter ce qui arrivera si nous ne changeons rien. Chaque matin, nous sortons du lit pour aller travailler parce que nous savons que si nous ne le faisons pas, il y aura des cons&#xE9;quences.<\/p>\n<p>C&#x2019;est aussi valide si vous voulez bouger plus. &#xC7;a peut vous sembler un peu malsain, mais c&#x2019;est important de vous rappeler ce qui arrivera si bouger ne fait pas partie de votre quotidien. Qu&#x2019;adviendra-t-il de votre sant&#xE9; et de votre bonheur?<\/p>\n<p>Bien s&#xFB;r, votre principale motivation ne devrait jamais &#xEA;tre la peur, mais garder en t&#xEA;te les cons&#xE9;quences de l&#x2019;inaction peut certainement vous aider &#xE0; vous motiver.<\/p>\n<p><strong>5. NE VOUS COMPAREZ PAS AUX AUTRES.<\/strong><\/p>\n<p>Avec les m&#xE9;dias sociaux, se comparer est plus facile que jamais. C&#x2019;est extr&#xEA;mement difficile de r&#xE9;sister &#xE0; la tentation de se comparer aux autres, mais le faire est surtout une bonne fa&#xE7;on de se d&#xE9;gonfler.<\/p>\n<p>&#xC0; la place, essayez de vous concentrer sur vous-m&#xEA;me, vos objectifs et vos priorit&#xE9;s. Souvenez-vous que nous sommes tous diff&#xE9;rents et qu&#x2019;essayer de vous comparer aux autres ne sera pas juste, ne vous aidera pas &#xE0; faire des progr&#xE8;s et n&#x2019;est pas une bonne fa&#xE7;on de vous motiver.<\/p>\n<p><strong>6. COMMENCEZ PAR LES PETITES CHOSES.<\/strong><\/p>\n<p>Vous n&#x2019;avez pas besoin de motivation pour vous brosser les dents ou pour attacher vos chaussures. Vous le faites tout simplement. Les petites t&#xE2;ches sont sans effort.<\/p>\n<p>Lorsque vous ne vous sentez pas motiv&#xE9;s, concentrez-vous sur des choses tellement faciles que vous n&#x2019;en aurez pas besoin. &#xC7;a peut vous sembler &#xE9;trange, mais &#xE7;a vous aidera &#xE0; adopter une nouvelle habitude.<\/p>\n<p><strong>7. AMUSEZ-VOUS!<\/strong><\/p>\n<p>Plus vous avez du plaisir, plus vous serez motiv&#xE9;s. Ne vous forcez pas &#xE0; faire des choses qui vous semblent &#xEA;tre une t&#xE2;che ou qui vous ennuient. Elles nuiront &#xE0; votre motivation.<\/p>\n<p>Plut&#xF4;t, faites quelque chose que vous aimez. M&#xEA;me si ce n&#x2019;est qu&#x2019;une petite marche. M&#xEA;me si ce n&#x2019;est que danser sur votre chanson pr&#xE9;f&#xE9;r&#xE9;e dans votre salon. M&#xEA;me si ce n&#x2019;est que quelques &#xE9;tirements pour vous aider &#xE0; vous d&#xE9;tendre.<\/p>\n<p><strong>UN R&#xCA;VE DEVENU R&#xC9;ALIT&#xC9;<\/strong><\/p>\n<p>Vous souhaitez voir votre motivation grandir avec le temps plut&#xF4;t que de dispara&#xEE;tre. Il se peut que &#xE7;a n&#x2019;arrive pas d&#xE8;s le premier essai. Et c&#x2019;est correct.<\/p>\n<p>Mais si vous vous en tenez &#xE0; l&#x2019;essentiel, en faisant des progr&#xE8;s constants, et que vous y prenez plaisir, vos souhaits pourraient bien finir par &#xEA;tre exauc&#xE9;s.[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La motivation peut facilement dispara&#xEE;tre. &#xC0; l&#x2019;approche de la nouvelle ann&#xE9;e, on s&#x2019;emballe et on est enthousiastes. Puis soudainement, une semaine passe et notre motivation s&#x2019;est envol&#xE9;e. Et on sait tous pourquoi &#x2014; faire des changements est difficile. C&#x2019;est facile de se dire qu&#x2019;on veut faire plus d&#x2019;exercice, mais c&#x2019;est plus facile &#xE0; dire qu&#x2019;&#xE0; [&#x2026;]<\/p>\n","protected":false},"author":3,"featured_media":261570,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","content-type":"","footnotes":""},"categories":[222,703],"tags":[781,430],"benefits":[],"class_list":["post-261574","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-trucs-et-conseils","category-exercice","tag-exercice","tag-objectifs"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.participaction.com\/fr\/wp-json\/wp\/v2\/posts\/261574","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.participaction.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.participaction.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.participaction.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.participaction.com\/fr\/wp-json\/wp\/v2\/comments?post=261574"}],"version-history":[{"count":0,"href":"https:\/\/dev.participaction.com\/fr\/wp-json\/wp\/v2\/posts\/261574\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.participaction.com\/fr\/wp-json\/wp\/v2\/media\/261570"}],"wp:attachment":[{"href":"https:\/\/dev.participaction.com\/fr\/wp-json\/wp\/v2\/media?parent=261574"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.participaction.com\/fr\/wp-json\/wp\/v2\/categories?post=261574"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.participaction.com\/fr\/wp-json\/wp\/v2\/tags?post=261574"},{"taxonomy":"benefits","embeddable":true,"href":"https:\/\/dev.participaction.com\/fr\/wp-json\/wp\/v2\/benefits?post=261574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}